{"id":1,"name":"dronesvalledeloja.com","url":"http:\/\/dronesvalledeloja.com","description":"","link":"https:\/\/dronesvalledeloja.com\/index.php\/author\/dronesvalledeloja-com\/","slug":"dronesvalledeloja-com","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0a947d014f1d77944d0624aa68ea61c9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0a947d014f1d77944d0624aa68ea61c9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0a947d014f1d77944d0624aa68ea61c9?s=96&d=mm&r=g"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>dronesvalledeloja.com, autor en dronesvalledeloja.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dronesvalledeloja.com\/index.php\/author\/dronesvalledeloja-com\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"dronesvalledeloja.com, autor en dronesvalledeloja.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dronesvalledeloja.com\/index.php\/author\/dronesvalledeloja-com\/\" \/>\n<meta property=\"og:site_name\" content=\"dronesvalledeloja.com\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/0a947d014f1d77944d0624aa68ea61c9?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\/\/dronesvalledeloja.com\/index.php\/author\/dronesvalledeloja-com\/\",\"url\":\"https:\/\/dronesvalledeloja.com\/index.php\/author\/dronesvalledeloja-com\/\",\"name\":\"dronesvalledeloja.com, autor en dronesvalledeloja.com\",\"isPartOf\":{\"@id\":\"https:\/\/dronesvalledeloja.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/dronesvalledeloja.com\/index.php\/author\/dronesvalledeloja-com\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dronesvalledeloja.com\/index.php\/author\/dronesvalledeloja-com\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dronesvalledeloja.com\/index.php\/author\/dronesvalledeloja-com\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dronesvalledeloja.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archivo de dronesvalledeloja.com\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dronesvalledeloja.com\/#website\",\"url\":\"https:\/\/dronesvalledeloja.com\/\",\"name\":\"dronesvalledeloja.com\",\"description\":\"Servicios A\u00e9reos Profesionales\",\"publisher\":{\"@id\":\"https:\/\/dronesvalledeloja.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dronesvalledeloja.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dronesvalledeloja.com\/#organization\",\"name\":\"dronesvalledeloja.com\",\"url\":\"https:\/\/dronesvalledeloja.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dronesvalledeloja.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dronesvalledeloja.com\/wp-content\/uploads\/2023\/12\/DO-1.png\",\"contentUrl\":\"https:\/\/dronesvalledeloja.com\/wp-content\/uploads\/2023\/12\/DO-1.png\",\"width\":500,\"height\":500,\"caption\":\"dronesvalledeloja.com\"},\"image\":{\"@id\":\"https:\/\/dronesvalledeloja.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dronesvalledeloja.com\/#\/schema\/person\/7b372441f412ca4bff43ce3c0d2ba9ec\",\"name\":\"dronesvalledeloja.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dronesvalledeloja.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0a947d014f1d77944d0624aa68ea61c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0a947d014f1d77944d0624aa68ea61c9?s=96&d=mm&r=g\",\"caption\":\"dronesvalledeloja.com\"},\"sameAs\":[\"http:\/\/dronesvalledeloja.com\"],\"mainEntityOfPage\":{\"@id\":\"https:\/\/dronesvalledeloja.com\/index.php\/author\/dronesvalledeloja-com\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"dronesvalledeloja.com, autor en dronesvalledeloja.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dronesvalledeloja.com\/index.php\/author\/dronesvalledeloja-com\/","og_locale":"en_US","og_type":"profile","og_title":"dronesvalledeloja.com, autor en dronesvalledeloja.com","og_url":"https:\/\/dronesvalledeloja.com\/index.php\/author\/dronesvalledeloja-com\/","og_site_name":"dronesvalledeloja.com","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/0a947d014f1d77944d0624aa68ea61c9?s=500&d=mm&r=g"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/dronesvalledeloja.com\/index.php\/author\/dronesvalledeloja-com\/","url":"https:\/\/dronesvalledeloja.com\/index.php\/author\/dronesvalledeloja-com\/","name":"dronesvalledeloja.com, autor en dronesvalledeloja.com","isPartOf":{"@id":"https:\/\/dronesvalledeloja.com\/#website"},"breadcrumb":{"@id":"https:\/\/dronesvalledeloja.com\/index.php\/author\/dronesvalledeloja-com\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dronesvalledeloja.com\/index.php\/author\/dronesvalledeloja-com\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dronesvalledeloja.com\/index.php\/author\/dronesvalledeloja-com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dronesvalledeloja.com\/"},{"@type":"ListItem","position":2,"name":"Archivo de dronesvalledeloja.com"}]},{"@type":"WebSite","@id":"https:\/\/dronesvalledeloja.com\/#website","url":"https:\/\/dronesvalledeloja.com\/","name":"dronesvalledeloja.com","description":"Servicios A\u00e9reos Profesionales","publisher":{"@id":"https:\/\/dronesvalledeloja.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dronesvalledeloja.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dronesvalledeloja.com\/#organization","name":"dronesvalledeloja.com","url":"https:\/\/dronesvalledeloja.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dronesvalledeloja.com\/#\/schema\/logo\/image\/","url":"https:\/\/dronesvalledeloja.com\/wp-content\/uploads\/2023\/12\/DO-1.png","contentUrl":"https:\/\/dronesvalledeloja.com\/wp-content\/uploads\/2023\/12\/DO-1.png","width":500,"height":500,"caption":"dronesvalledeloja.com"},"image":{"@id":"https:\/\/dronesvalledeloja.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dronesvalledeloja.com\/#\/schema\/person\/7b372441f412ca4bff43ce3c0d2ba9ec","name":"dronesvalledeloja.com","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dronesvalledeloja.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0a947d014f1d77944d0624aa68ea61c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a947d014f1d77944d0624aa68ea61c9?s=96&d=mm&r=g","caption":"dronesvalledeloja.com"},"sameAs":["http:\/\/dronesvalledeloja.com"],"mainEntityOfPage":{"@id":"https:\/\/dronesvalledeloja.com\/index.php\/author\/dronesvalledeloja-com\/"}}]}},"is_super_admin":true,"woocommerce_meta":{"variable_product_tour_shown":"","wc_payments_overview_inbox_last_read":"","activity_panel_inbox_last_read":"","activity_panel_reviews_last_read":"","categories_report_columns":"","coupons_report_columns":"","customers_report_columns":"","orders_report_columns":"","products_report_columns":"","revenue_report_columns":"","taxes_report_columns":"","variations_report_columns":"","dashboard_sections":"","dashboard_chart_type":"","dashboard_chart_interval":"","dashboard_leaderboard_rows":"","homepage_layout":"","homepage_stats":"","task_list_tracked_started_tasks":"{\"customize-store\":1}","help_panel_highlight_shown":"","android_app_banner_dismissed":"","launch_your_store_tour_hidden":"","coming_soon_banner_dismissed":""},"_links":{"self":[{"href":"https:\/\/dronesvalledeloja.com\/index.php\/wp-json\/wp\/v2\/users\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dronesvalledeloja.com\/index.php\/wp-json\/wp\/v2\/users"}]}}